{"id":12163,"date":"2025-04-21T10:13:48","date_gmt":"2025-04-21T14:13:48","guid":{"rendered":"https:\/\/www.humanware.com\/support-training\/mise-a-jour-de-stellartrek-lisez-des-livres-et-detectez-les-feux-de-circulation-grace-a-lia\/"},"modified":"2025-04-23T09:10:41","modified_gmt":"2025-04-23T13:10:41","slug":"stellartrek-update-read-books-detect-traffic-lights-with-ai","status":"publish","type":"post","link":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/","title":{"rendered":"Mise \u00e0 jour StellarTrek: Lecteur de livres et d\u00e9tection des feux de circulation avec l\u2019IA!"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12133\" title=\"Image du StellarTrek sur une \u00e9tag\u00e8re, entour\u00e9 de livres color\u00e9s.\" src=\"https:\/\/www.humanware.com\/wp-content\/uploads\/2025\/04\/Bandeau-StellarTrek-Promo-1-300x135.jpg\" alt=\"Image du StellarTrek sur une \u00e9tag\u00e8re, entour\u00e9 de livres color\u00e9s.\" width=\"1100\" height=\"495\" srcset=\"https:\/\/www.humanware.com\/wp-content\/uploads\/2025\/04\/Bandeau-StellarTrek-Promo-1-300x135.jpg 300w, https:\/\/www.humanware.com\/wp-content\/uploads\/2025\/04\/Bandeau-StellarTrek-Promo-1-768x346.jpg 768w, https:\/\/www.humanware.com\/wp-content\/uploads\/2025\/04\/Bandeau-StellarTrek-Promo-1.jpg 1000w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>Vous l\u2019avez demand\u00e9, nous vous avons \u00e9cout\u00e9! Cette mise \u00e0 jour du StellarTrek comprend<strong>\u00a0deux nouvelles fonctionnalit\u00e9s\u00a0<\/strong>con\u00e7ues pour enrichir votre autonomie et votre exp\u00e9rience de mobilit\u00e9.<\/p>\n<h3>Lecteur de livres int\u00e9gr\u00e9<\/h3>\n<p>Lisez vos livres pendant que vous naviguez! Sur le StellarTrek, vous pourrez, contrairement au Victor Reader Trek, lire vos livres pendant que vous circulez \u00e0 l\u2019ext\u00e9rieur. \u00c9coutez vos livres sur des services comme Bookshare tout en recevant les instructions de navigation ou en v\u00e9rifiant votre emplacement avec la touche \u00ab\u202fO\u00f9 suis-je\u202f\u00bb.\u00a0(Note: Les livres textes sont support\u00e9s, les livres audio ne le sont pas pour le moment)<\/p>\n<h3>D\u00e9tection des feux de circulation pour les pi\u00e9tons (beta)<\/h3>\n<div style=\"display: flex; flex-wrap: wrap; align-items: center; max-width: 1100px; margin: 0 auto;\">\n<div style=\"flex: 2; min-width: 250px;\">\n<p>Naviguez en toute confiance! Le StellarTrek utilise d\u00e9sormais l\u2019IA pour d\u00e9tecter les feux de circulation, ce qui vous donne plus d\u2019information pour vous aider \u00e0 d\u00e9cider quand traverser. La s\u00e9curit\u00e9 \u00e9tant notre priorit\u00e9 absolue, nous lan\u00e7ons cette fonctionnalit\u00e9 en mode<strong>\u00a0beta\u00a0<\/strong>et y apporterons des am\u00e9liorations avec le temps.<\/p>\n<\/div>\n<p><!-- Bloc image --><\/p>\n<div style=\"flex: 1; min-width: 150px; text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" style=\"max-width: 100%; height: auto; padding: 10px;\" title=\"Image d'un feu de circulation. Le rouge indique d'arr\u00eater, avec un symbole de main, tandis que le vert invite les pi\u00e9tons \u00e0 avancer.\" src=\"https:\/\/www.humanware.com\/trafic-light\/\" alt=\"Image d'un feu de circulation. Le rouge indique d'arr\u00eater, avec un symbole de main, tandis que le vert invite les pi\u00e9tons \u00e0 avancer.\" width=\"250\" height=\"250\" \/><\/div>\n<\/div>\n<p>Cette mise \u00e0 jour inclut \u00e9galement plusieurs correctifs de bogues et des am\u00e9liorations pour rendre votre exp\u00e9rience avec le StellarTrek encore meilleure.<\/p>\n<h3>Lib\u00e9rez le potentiel de votre StellarTrek &#8211; d\u00e9couvrez ce qui est nouveau et am\u00e9lior\u00e9<\/h3>\n<p style=\"color: #000 !important;\">Explorez les derni\u00e8res fonctionnalit\u00e9s d\u00e8s maintenant sur la\u00a0<a style=\"color: #4b7a88 !important; font-weight: 700 !important;\" href=\"https:\/\/www.humanware.com\/support\/stellartrek\/\" rel=\"noopener\">page soutien du StellarTrek<\/a>.<\/p>\n<p>Avec ces nouvelles fonctionnalit\u00e9s puissantes, la derni\u00e8re mise \u00e0 jour de StellarTrek est con\u00e7ue pour vous permettre de rester inform\u00e9, ind\u00e9pendant et en mouvement &#8211; parce qu&rsquo;avec StellarTrek, vous \u00eates sur la bonne voie.<\/p>\n<h3 class=\"canada\" style=\"text-align: left;\"><a style=\"color: #4b7a88 !important; font-weight: 700 !important;\" href=\"https:\/\/store.humanware.com\/hca\/stellartrek.html?___store=ca_fr\" rel=\"noopener\">Procurez-vous le v\u00f4tre d\u00e8s aujourd\u2019hui.<\/a><\/h3>\n<h3 class=\"international\" style=\"text-align: left;\"><a style=\"color: #4b7a88 !important; font-weight: 700 !important;\" href=\"https:\/\/store.humanware.com\/int\/stellartrek.html?___store=int_fr\" rel=\"noopener\">Procurez-vous le v\u00f4tre d\u00e8s aujourd\u2019hui.<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Vous l\u2019avez demand\u00e9, nous vous avons \u00e9cout\u00e9! Cette mise \u00e0 jour du StellarTrek comprend\u00a0deux nouvelles fonctionnalit\u00e9s\u00a0con\u00e7ues pour enrichir votre autonomie et votre exp\u00e9rience de mobilit\u00e9. Lecteur de livres int\u00e9gr\u00e9 Lisez vos livres pendant que vous naviguez! Sur le StellarTrek, vous pourrez, contrairement au Victor Reader Trek, lire vos livres pendant que vous circulez \u00e0 l\u2019ext\u00e9rieur. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":12160,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[77,76],"tags":[],"class_list":["post-12163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-annonces-de-produits","category-nouvelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mise \u00e0 jour StellarTrek: Lecteur de livres et d\u00e9tection des feux de circulation avec l\u2019IA! - HumanWare<\/title>\n<meta name=\"description\" content=\"Vous l\u2019avez demand\u00e9, nous vous avons \u00e9cout\u00e9! Cette mise \u00e0 jour du StellarTrek comprend deux nouvelles fonctionnalit\u00e9s con\u00e7ues pour enrichir votre autonomie et votre exp\u00e9rience de mobilit\u00e9. Lecteur de livres int\u00e9gr\u00e9Lisez vos livres pendant que vous naviguez! Sur le StellarTrek, vous pourrez, contrairement au Victor Reader Trek, lire vos livres pendant que vous circulez \u00e0 l\u2019ext\u00e9rieur. \u00c9coutez vos livres sur des services comme Bookshare tout en recevant les instructions de navigation ou en v\u00e9rifiant votre emplacement avec la touche \u00ab\u202fO\u00f9 suis-je\u202f\u00bb. (Note: Les livres textes sont support\u00e9s, les livres audio ne le sont pas pour le moment)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mise \u00e0 jour StellarTrek: Lecteur de livres et d\u00e9tection des feux de circulation avec l\u2019IA! - HumanWare\" \/>\n<meta property=\"og:description\" content=\"Vous l\u2019avez demand\u00e9, nous vous avons \u00e9cout\u00e9! Cette mise \u00e0 jour du StellarTrek comprend deux nouvelles fonctionnalit\u00e9s con\u00e7ues pour enrichir votre autonomie et votre exp\u00e9rience de mobilit\u00e9. Lecteur de livres int\u00e9gr\u00e9Lisez vos livres pendant que vous naviguez! Sur le StellarTrek, vous pourrez, contrairement au Victor Reader Trek, lire vos livres pendant que vous circulez \u00e0 l\u2019ext\u00e9rieur. \u00c9coutez vos livres sur des services comme Bookshare tout en recevant les instructions de navigation ou en v\u00e9rifiant votre emplacement avec la touche \u00ab\u202fO\u00f9 suis-je\u202f\u00bb. (Note: Les livres textes sont support\u00e9s, les livres audio ne le sont pas pour le moment)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/\" \/>\n<meta property=\"og:site_name\" content=\"HumanWare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/humanware\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-21T14:13:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-23T13:10:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.humanware.com\/wp-content\/uploads\/2025\/04\/StellarTrek-346X300.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"346\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Natacha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natacha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/stellartrek-update-read-books-detect-traffic-lights-with-ai\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/stellartrek-update-read-books-detect-traffic-lights-with-ai\\\/\"},\"author\":{\"name\":\"Natacha\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#\\\/schema\\\/person\\\/d38997639f2af0f29e505b296196f4a7\"},\"headline\":\"Mise \u00e0 jour StellarTrek: Lecteur de livres et d\u00e9tection des feux de circulation avec l\u2019IA!\",\"datePublished\":\"2025-04-21T14:13:48+00:00\",\"dateModified\":\"2025-04-23T13:10:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/stellartrek-update-read-books-detect-traffic-lights-with-ai\\\/\"},\"wordCount\":297,\"publisher\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/stellartrek-update-read-books-detect-traffic-lights-with-ai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.humanware.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/StellarTrek-346X300.jpg\",\"articleSection\":[\"Annonces de produits\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/stellartrek-update-read-books-detect-traffic-lights-with-ai\\\/\",\"url\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/stellartrek-update-read-books-detect-traffic-lights-with-ai\\\/\",\"name\":\"Mise \u00e0 jour StellarTrek: Lecteur de livres et d\u00e9tection des feux de circulation avec l\u2019IA! - HumanWare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/stellartrek-update-read-books-detect-traffic-lights-with-ai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/stellartrek-update-read-books-detect-traffic-lights-with-ai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.humanware.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/StellarTrek-346X300.jpg\",\"datePublished\":\"2025-04-21T14:13:48+00:00\",\"dateModified\":\"2025-04-23T13:10:41+00:00\",\"description\":\"Vous l\u2019avez demand\u00e9, nous vous avons \u00e9cout\u00e9! Cette mise \u00e0 jour du StellarTrek comprend deux nouvelles fonctionnalit\u00e9s con\u00e7ues pour enrichir votre autonomie et votre exp\u00e9rience de mobilit\u00e9. Lecteur de livres int\u00e9gr\u00e9Lisez vos livres pendant que vous naviguez! Sur le StellarTrek, vous pourrez, contrairement au Victor Reader Trek, lire vos livres pendant que vous circulez \u00e0 l\u2019ext\u00e9rieur. \u00c9coutez vos livres sur des services comme Bookshare tout en recevant les instructions de navigation ou en v\u00e9rifiant votre emplacement avec la touche \u00ab\u202fO\u00f9 suis-je\u202f\u00bb. (Note: Les livres textes sont support\u00e9s, les livres audio ne le sont pas pour le moment)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/stellartrek-update-read-books-detect-traffic-lights-with-ai\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/stellartrek-update-read-books-detect-traffic-lights-with-ai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/stellartrek-update-read-books-detect-traffic-lights-with-ai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.humanware.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/StellarTrek-346X300.jpg\",\"contentUrl\":\"https:\\\/\\\/www.humanware.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/StellarTrek-346X300.jpg\",\"width\":346,\"height\":300,\"caption\":\"Image du StellarTrek sur une \u00e9tag\u00e8re, entour\u00e9 de livres color\u00e9s.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/stellartrek-update-read-books-detect-traffic-lights-with-ai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/category\\\/nouvelles\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mise \u00e0 jour StellarTrek: Lecteur de livres et d\u00e9tection des feux de circulation avec l\u2019IA!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/\",\"name\":\"HumanWare\",\"description\":\"Solutions pour basse vision et c\u00e9cit\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#organization\",\"name\":\"HumanWare\",\"url\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.humanware.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-HW.jpg\",\"contentUrl\":\"https:\\\/\\\/www.humanware.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-HW.jpg\",\"width\":1000,\"height\":667,\"caption\":\"HumanWare\"},\"image\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/humanware\\\/\",\"https:\\\/\\\/ca.linkedin.com\\\/company\\\/humanware\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#\\\/schema\\\/person\\\/d38997639f2af0f29e505b296196f4a7\",\"name\":\"Natacha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/609632888407e6eb44e59b600082fb4bd01895796c5293abded07e5942c828a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/609632888407e6eb44e59b600082fb4bd01895796c5293abded07e5942c828a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/609632888407e6eb44e59b600082fb4bd01895796c5293abded07e5942c828a9?s=96&d=mm&r=g\",\"caption\":\"Natacha\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mise \u00e0 jour StellarTrek: Lecteur de livres et d\u00e9tection des feux de circulation avec l\u2019IA! - HumanWare","description":"Vous l\u2019avez demand\u00e9, nous vous avons \u00e9cout\u00e9! Cette mise \u00e0 jour du StellarTrek comprend deux nouvelles fonctionnalit\u00e9s con\u00e7ues pour enrichir votre autonomie et votre exp\u00e9rience de mobilit\u00e9. Lecteur de livres int\u00e9gr\u00e9Lisez vos livres pendant que vous naviguez! Sur le StellarTrek, vous pourrez, contrairement au Victor Reader Trek, lire vos livres pendant que vous circulez \u00e0 l\u2019ext\u00e9rieur. \u00c9coutez vos livres sur des services comme Bookshare tout en recevant les instructions de navigation ou en v\u00e9rifiant votre emplacement avec la touche \u00ab\u202fO\u00f9 suis-je\u202f\u00bb. (Note: Les livres textes sont support\u00e9s, les livres audio ne le sont pas pour le moment)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/","og_locale":"fr_FR","og_type":"article","og_title":"Mise \u00e0 jour StellarTrek: Lecteur de livres et d\u00e9tection des feux de circulation avec l\u2019IA! - HumanWare","og_description":"Vous l\u2019avez demand\u00e9, nous vous avons \u00e9cout\u00e9! Cette mise \u00e0 jour du StellarTrek comprend deux nouvelles fonctionnalit\u00e9s con\u00e7ues pour enrichir votre autonomie et votre exp\u00e9rience de mobilit\u00e9. Lecteur de livres int\u00e9gr\u00e9Lisez vos livres pendant que vous naviguez! Sur le StellarTrek, vous pourrez, contrairement au Victor Reader Trek, lire vos livres pendant que vous circulez \u00e0 l\u2019ext\u00e9rieur. \u00c9coutez vos livres sur des services comme Bookshare tout en recevant les instructions de navigation ou en v\u00e9rifiant votre emplacement avec la touche \u00ab\u202fO\u00f9 suis-je\u202f\u00bb. (Note: Les livres textes sont support\u00e9s, les livres audio ne le sont pas pour le moment)","og_url":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/","og_site_name":"HumanWare","article_publisher":"https:\/\/www.facebook.com\/humanware\/","article_published_time":"2025-04-21T14:13:48+00:00","article_modified_time":"2025-04-23T13:10:41+00:00","og_image":[{"width":346,"height":300,"url":"https:\/\/www.humanware.com\/wp-content\/uploads\/2025\/04\/StellarTrek-346X300.jpg","type":"image\/jpeg"}],"author":"Natacha","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Natacha","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/#article","isPartOf":{"@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/"},"author":{"name":"Natacha","@id":"https:\/\/www.humanware.com\/fr\/#\/schema\/person\/d38997639f2af0f29e505b296196f4a7"},"headline":"Mise \u00e0 jour StellarTrek: Lecteur de livres et d\u00e9tection des feux de circulation avec l\u2019IA!","datePublished":"2025-04-21T14:13:48+00:00","dateModified":"2025-04-23T13:10:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/"},"wordCount":297,"publisher":{"@id":"https:\/\/www.humanware.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/#primaryimage"},"thumbnailUrl":"https:\/\/www.humanware.com\/wp-content\/uploads\/2025\/04\/StellarTrek-346X300.jpg","articleSection":["Annonces de produits","Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/","url":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/","name":"Mise \u00e0 jour StellarTrek: Lecteur de livres et d\u00e9tection des feux de circulation avec l\u2019IA! - HumanWare","isPartOf":{"@id":"https:\/\/www.humanware.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/#primaryimage"},"image":{"@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/#primaryimage"},"thumbnailUrl":"https:\/\/www.humanware.com\/wp-content\/uploads\/2025\/04\/StellarTrek-346X300.jpg","datePublished":"2025-04-21T14:13:48+00:00","dateModified":"2025-04-23T13:10:41+00:00","description":"Vous l\u2019avez demand\u00e9, nous vous avons \u00e9cout\u00e9! Cette mise \u00e0 jour du StellarTrek comprend deux nouvelles fonctionnalit\u00e9s con\u00e7ues pour enrichir votre autonomie et votre exp\u00e9rience de mobilit\u00e9. Lecteur de livres int\u00e9gr\u00e9Lisez vos livres pendant que vous naviguez! Sur le StellarTrek, vous pourrez, contrairement au Victor Reader Trek, lire vos livres pendant que vous circulez \u00e0 l\u2019ext\u00e9rieur. \u00c9coutez vos livres sur des services comme Bookshare tout en recevant les instructions de navigation ou en v\u00e9rifiant votre emplacement avec la touche \u00ab\u202fO\u00f9 suis-je\u202f\u00bb. (Note: Les livres textes sont support\u00e9s, les livres audio ne le sont pas pour le moment)","breadcrumb":{"@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/#primaryimage","url":"https:\/\/www.humanware.com\/wp-content\/uploads\/2025\/04\/StellarTrek-346X300.jpg","contentUrl":"https:\/\/www.humanware.com\/wp-content\/uploads\/2025\/04\/StellarTrek-346X300.jpg","width":346,"height":300,"caption":"Image du StellarTrek sur une \u00e9tag\u00e8re, entour\u00e9 de livres color\u00e9s."},{"@type":"BreadcrumbList","@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/stellartrek-update-read-books-detect-traffic-lights-with-ai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.humanware.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/www.humanware.com\/fr\/category\/nouvelles\/"},{"@type":"ListItem","position":3,"name":"Mise \u00e0 jour StellarTrek: Lecteur de livres et d\u00e9tection des feux de circulation avec l\u2019IA!"}]},{"@type":"WebSite","@id":"https:\/\/www.humanware.com\/fr\/#website","url":"https:\/\/www.humanware.com\/fr\/","name":"HumanWare","description":"Solutions pour basse vision et c\u00e9cit\u00e9","publisher":{"@id":"https:\/\/www.humanware.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.humanware.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.humanware.com\/fr\/#organization","name":"HumanWare","url":"https:\/\/www.humanware.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.humanware.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.humanware.com\/wp-content\/uploads\/2024\/12\/Logo-HW.jpg","contentUrl":"https:\/\/www.humanware.com\/wp-content\/uploads\/2024\/12\/Logo-HW.jpg","width":1000,"height":667,"caption":"HumanWare"},"image":{"@id":"https:\/\/www.humanware.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/humanware\/","https:\/\/ca.linkedin.com\/company\/humanware"]},{"@type":"Person","@id":"https:\/\/www.humanware.com\/fr\/#\/schema\/person\/d38997639f2af0f29e505b296196f4a7","name":"Natacha","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/609632888407e6eb44e59b600082fb4bd01895796c5293abded07e5942c828a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/609632888407e6eb44e59b600082fb4bd01895796c5293abded07e5942c828a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/609632888407e6eb44e59b600082fb4bd01895796c5293abded07e5942c828a9?s=96&d=mm&r=g","caption":"Natacha"}}]}},"_links":{"self":[{"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/posts\/12163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/comments?post=12163"}],"version-history":[{"count":8,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/posts\/12163\/revisions"}],"predecessor-version":[{"id":12165,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/posts\/12163\/revisions\/12165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/media\/12160"}],"wp:attachment":[{"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/media?parent=12163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/categories?post=12163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/tags?post=12163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}