{"id":17915,"date":"2026-01-10T15:07:31","date_gmt":"2026-01-10T20:07:31","guid":{"rendered":"https:\/\/www.humanware.com\/?p=17915"},"modified":"2026-01-13T15:55:23","modified_gmt":"2026-01-13T20:55:23","slug":"supporting-global-movement-for-braille-literacy","status":"publish","type":"post","link":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/","title":{"rendered":"Soutenir un mouvement mondial pour la litt\u00e9ratie braille"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-17872 size-full\" title=\"Un enfant africain utilise un appareil braille en classe, accompagn\u00e9 de son enseignante.\" src=\"https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/ICEVI\u2013WBU.jpg\" alt=\"Un enfant africain utilise un appareil braille en classe, accompagn\u00e9 de son enseignante.\" width=\"1100\" height=\"495\" srcset=\"https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/ICEVI\u2013WBU.jpg 1100w, https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/ICEVI\u2013WBU-300x135.jpg 300w, https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/ICEVI\u2013WBU-1024x461.jpg 1024w, https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/ICEVI\u2013WBU-768x346.jpg 768w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>HumanWare est fi\u00e8re de soutenir la <a style=\"color: #4b7a88;\" href=\"https:\/\/icevi.org\/icevi-wbu-global-braille-literacy-campaign\/\" target=\"_blank\" rel=\"noopener\"><strong>campagne mondiale pour la litt\u00e9ratie braille ICEVI\u2013WBU<\/strong><\/a> en tant que commanditaire Diamant, et de se joindre \u00e0 un mouvement international d\u00e9di\u00e9 \u00e0 l\u2019avancement de la litt\u00e9ratie braille et de l\u2019inclusion des personnes qui sont aveugles, sourdes-aveugles ou qui ont une basse vision.<\/p>\n<p style=\"padding-bottom: 15px;\">Dirig\u00e9e par le <strong><a style=\"color: #4b7a88;\" href=\"https:\/\/icevi.org\/icevi-wbu-global-braille-literacy-campaign\/\" target=\"_blank\" rel=\"noopener\">Conseil international pour l\u2019\u00e9ducation des personnes ayant une d\u00e9ficience visuelle (ICEVI)<\/a><\/strong> et l\u2019<strong><a style=\"color: #4b7a88;\" href=\"https:\/\/wbu.ngo\/fr\/a-propos-de\/qui-nous-sommes\" target=\"_blank\" rel=\"noopener\">Union mondiale des aveugles (WBU)<\/a><\/strong>, la campagne rassemble des \u00e9ducateurs, des d\u00e9fenseurs, des familles, des organisations et des partenaires autour d\u2019un objectif commun : faire en sorte que le braille demeure une base essentielle de la lecture, de l\u2019\u00e9criture, de l\u2019apprentissage et de l\u2019autonomie \u00e0 toutes les \u00e9tapes de la vie.<\/p>\n<p style=\"text-align: center; margin-top: 25px;\"><iframe title=\"L'alphab\u00e9tisation en braille et les solutions HumanWare\" src=\"https:\/\/www.youtube.com\/embed\/H4VFPYfzGVc\" height=\"500\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_end\"><\/span><br \/>\n<\/iframe><\/p>\n<p>Partout dans le monde, de nombreux enfants et adultes font encore face \u00e0 des obstacles pour acc\u00e9der \u00e0 un enseignement du braille de qualit\u00e9, \u00e0 des mat\u00e9riels d\u2019apprentissage adapt\u00e9s et \u00e0 des technologies accessibles. La campagne mondiale pour la litt\u00e9ratie braille vise \u00e0 combler ces \u00e9carts en favorisant un acc\u00e8s \u00e9quitable au braille, tant en formats tactiles que num\u00e9riques, en soutenant des pratiques p\u00e9dagogiques efficaces et en encourageant la collaboration entre les syst\u00e8mes \u00e9ducatifs et les communaut\u00e9s.<\/p>\n<p>La campagne s\u2019articule autour de trois axes : la sensibilisation et le plaidoyer, le partage d\u2019information et la recherche. Gr\u00e2ce \u00e0 des contenus de sensibilisation accessibles, \u00e0 des ressources partag\u00e9es pour les \u00e9ducateurs et les familles, ainsi qu\u2019\u00e0 des initiatives de recherche \u00e0 l\u2019\u00e9chelle mondiale, elle cherche \u00e0 renforcer la litt\u00e9ratie braille et \u00e0 d\u00e9velopper une base de connaissances plus solide pour \u00e9clairer les politiques et les pratiques.<\/p>\n<p>La campagne mondiale pour la litt\u00e9ratie braille a \u00e9t\u00e9 officiellement lanc\u00e9e lors de la <strong>Journ\u00e9e mondiale du braille, le 4 janvier 2026<\/strong>, et se d\u00e9roulera sur une p\u00e9riode de deux ans, soit en 2026 et 2027.<\/p>\n<div style=\"display: flex; flex-wrap: wrap; align-items: center; max-width: 1100px; margin: 0 auto;\">\n<div style=\"flex: 2; min-width: 250px;\">\n<p><strong>Frances Gentle, <\/strong>ancienne pr\u00e9sidente de l\u2019ICEVI, a soulign\u00e9 l\u2019importance de l\u2019action collective pour faire progresser la litt\u00e9ratie braille \u00e0 l\u2019\u00e9chelle mondiale :<\/p>\n<p>\u00ab<em> Le changement mondial se produit lorsque des organisations s\u2019engagent avec intention. L\u2019engagement de HumanWare \u00e0 titre de commanditaire Diamant acc\u00e9l\u00e8re les progr\u00e8s vers un monde o\u00f9 chaque enfant qui a besoin du braille peut apprendre, lire et s\u2019\u00e9panouir.<\/em> \u00bb<\/p>\n<\/div>\n<p><!-- Bloc image --><\/p>\n<div style=\"flex: 1; min-width: 150px; text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-17878\" title=\"Frances Gentle\" src=\"https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/Frances-Gentle-257x300.jpg\" alt=\"Frances Gentle\" width=\"200\" height=\"233\" srcset=\"https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/Frances-Gentle-257x300.jpg 257w, https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/Frances-Gentle.jpg 300w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/div>\n<\/div>\n<div style=\"display: flex; flex-wrap: wrap; align-items: center; max-width: 1100px; margin: 0 auto;\">\n<p style=\"padding-top: 30px; padding-bottom: 15px;\">HumanWare consid\u00e8re \u00e9galement ce partenariat comme une occasion de travailler aux c\u00f4t\u00e9s d\u2019organisations qui \u0153uvrent depuis longtemps pour l\u2019avancement de la litt\u00e9ratie braille \u00e0 l\u2019\u00e9chelle internationale.<\/p>\n<div style=\"display: flex; flex-wrap: wrap; align-items: center; max-width: 1100px; margin: 0 auto;\">\n<div style=\"flex: 2; min-width: 250px;\">\n<p>Comme l\u2019a soulign\u00e9<strong> Pedro Polson<\/strong>, chef de la direction de HumanWare pour l\u2019Europe, le Moyen-Orient et l\u2019Afrique :<\/p>\n<p>\u00ab<em> HumanWare est fi\u00e8re de se tenir aux c\u00f4t\u00e9s de l\u2019ICEVI et de la WBU pour promouvoir la litt\u00e9ratie braille \u00e0 l\u2019\u00e9chelle mondiale et veiller \u00e0 ce que chaque personne qui est aveugle ou qui a une basse vision dispose des outils n\u00e9cessaires pour apprendre, s\u2019\u00e9panouir et participer pleinement \u00e0 la soci\u00e9t\u00e9.<\/em> \u00bb<\/p>\n<\/div>\n<p><!-- Bloc image --><\/p>\n<div style=\"flex: 1; min-width: 150px; text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-17880\" title=\"Pedro Polson\" src=\"https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/Pedro-Polson-257x300.jpg\" alt=\"Pedro Polson\" width=\"200\" height=\"233\" srcset=\"https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/Pedro-Polson-257x300.jpg 257w, https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/Pedro-Polson.jpg 300w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/div>\n<\/div>\n<\/div>\n<p style=\"padding-top: 30px;\">La participation de HumanWare refl\u00e8te la conviction que l\u2019acc\u00e8s \u00e0 la litt\u00e9ratie braille est essentiel \u00e0 une pleine participation \u00e0 l\u2019\u00e9ducation, \u00e0 l\u2019emploi et \u00e0 la vie quotidienne. Nous sommes honor\u00e9s de nous joindre \u00e0 cet effort mondial et de soutenir une campagne qui place les personnes, la litt\u00e9ratie et l\u2019inclusion au c\u0153ur de ses priorit\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>HumanWare est fi\u00e8re de soutenir la campagne mondiale pour la litt\u00e9ratie braille ICEVI\u2013WBU en tant que commanditaire Diamant, et de se joindre \u00e0 un mouvement international d\u00e9di\u00e9 \u00e0 l\u2019avancement de la litt\u00e9ratie braille et de l\u2019inclusion des personnes qui sont aveugles, sourdes-aveugles ou qui ont une basse vision. Dirig\u00e9e par le Conseil international pour l\u2019\u00e9ducation [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":17875,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[76,75],"tags":[],"class_list":["post-17915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","category-nouvelles-de-l-entreprise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soutenir un mouvement mondial pour la litt\u00e9ratie braille - HumanWare<\/title>\n<meta name=\"description\" content=\"HumanWare est fi\u00e8re de soutenir la campagne mondiale pour la litt\u00e9ratie braille ICEVI\u2013WBU en tant que commanditaire Diamant, et de se joindre \u00e0 un mouvement international d\u00e9di\u00e9 \u00e0 l\u2019avancement de la litt\u00e9ratie braille et de l\u2019inclusion des personnes qui sont aveugles, sourdes-aveugles ou qui ont une basse vision.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soutenir un mouvement mondial pour la litt\u00e9ratie braille - HumanWare\" \/>\n<meta property=\"og:description\" content=\"HumanWare est fi\u00e8re de soutenir la campagne mondiale pour la litt\u00e9ratie braille ICEVI\u2013WBU en tant que commanditaire Diamant, et de se joindre \u00e0 un mouvement international d\u00e9di\u00e9 \u00e0 l\u2019avancement de la litt\u00e9ratie braille et de l\u2019inclusion des personnes qui sont aveugles, sourdes-aveugles ou qui ont une basse vision.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/\" \/>\n<meta property=\"og:site_name\" content=\"HumanWare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/humanware\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-10T20:07:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-13T20:55:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/ICEVI\u2013WBU-thumb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"346\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Natacha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natacha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/supporting-global-movement-for-braille-literacy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/supporting-global-movement-for-braille-literacy\\\/\"},\"author\":{\"name\":\"Natacha\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#\\\/schema\\\/person\\\/d38997639f2af0f29e505b296196f4a7\"},\"headline\":\"Soutenir un mouvement mondial pour la litt\u00e9ratie braille\",\"datePublished\":\"2026-01-10T20:07:31+00:00\",\"dateModified\":\"2026-01-13T20:55:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/supporting-global-movement-for-braille-literacy\\\/\"},\"wordCount\":562,\"publisher\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/supporting-global-movement-for-braille-literacy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.humanware.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ICEVI\u2013WBU-thumb.jpg\",\"articleSection\":[\"Nouvelles\",\"Nouvelles de l'entreprise\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/supporting-global-movement-for-braille-literacy\\\/\",\"url\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/supporting-global-movement-for-braille-literacy\\\/\",\"name\":\"Soutenir un mouvement mondial pour la litt\u00e9ratie braille - HumanWare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/supporting-global-movement-for-braille-literacy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/supporting-global-movement-for-braille-literacy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.humanware.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ICEVI\u2013WBU-thumb.jpg\",\"datePublished\":\"2026-01-10T20:07:31+00:00\",\"dateModified\":\"2026-01-13T20:55:23+00:00\",\"description\":\"HumanWare est fi\u00e8re de soutenir la campagne mondiale pour la litt\u00e9ratie braille ICEVI\u2013WBU en tant que commanditaire Diamant, et de se joindre \u00e0 un mouvement international d\u00e9di\u00e9 \u00e0 l\u2019avancement de la litt\u00e9ratie braille et de l\u2019inclusion des personnes qui sont aveugles, sourdes-aveugles ou qui ont une basse vision.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/supporting-global-movement-for-braille-literacy\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/supporting-global-movement-for-braille-literacy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/supporting-global-movement-for-braille-literacy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.humanware.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ICEVI\u2013WBU-thumb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.humanware.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ICEVI\u2013WBU-thumb.jpg\",\"width\":346,\"height\":300,\"caption\":\"Un enfant africain utilise un appareil braille en classe, accompagn\u00e9 de son enseignante.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/nouvelles\\\/supporting-global-movement-for-braille-literacy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/category\\\/nouvelles\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Soutenir un mouvement mondial pour la litt\u00e9ratie braille\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/\",\"name\":\"HumanWare\",\"description\":\"Solutions pour basse vision et c\u00e9cit\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#organization\",\"name\":\"HumanWare\",\"url\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.humanware.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-HW.jpg\",\"contentUrl\":\"https:\\\/\\\/www.humanware.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-HW.jpg\",\"width\":1000,\"height\":667,\"caption\":\"HumanWare\"},\"image\":{\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/humanware\\\/\",\"https:\\\/\\\/ca.linkedin.com\\\/company\\\/humanware\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.humanware.com\\\/fr\\\/#\\\/schema\\\/person\\\/d38997639f2af0f29e505b296196f4a7\",\"name\":\"Natacha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/609632888407e6eb44e59b600082fb4bd01895796c5293abded07e5942c828a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/609632888407e6eb44e59b600082fb4bd01895796c5293abded07e5942c828a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/609632888407e6eb44e59b600082fb4bd01895796c5293abded07e5942c828a9?s=96&d=mm&r=g\",\"caption\":\"Natacha\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soutenir un mouvement mondial pour la litt\u00e9ratie braille - HumanWare","description":"HumanWare est fi\u00e8re de soutenir la campagne mondiale pour la litt\u00e9ratie braille ICEVI\u2013WBU en tant que commanditaire Diamant, et de se joindre \u00e0 un mouvement international d\u00e9di\u00e9 \u00e0 l\u2019avancement de la litt\u00e9ratie braille et de l\u2019inclusion des personnes qui sont aveugles, sourdes-aveugles ou qui ont une basse vision.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/","og_locale":"fr_FR","og_type":"article","og_title":"Soutenir un mouvement mondial pour la litt\u00e9ratie braille - HumanWare","og_description":"HumanWare est fi\u00e8re de soutenir la campagne mondiale pour la litt\u00e9ratie braille ICEVI\u2013WBU en tant que commanditaire Diamant, et de se joindre \u00e0 un mouvement international d\u00e9di\u00e9 \u00e0 l\u2019avancement de la litt\u00e9ratie braille et de l\u2019inclusion des personnes qui sont aveugles, sourdes-aveugles ou qui ont une basse vision.","og_url":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/","og_site_name":"HumanWare","article_publisher":"https:\/\/www.facebook.com\/humanware\/","article_published_time":"2026-01-10T20:07:31+00:00","article_modified_time":"2026-01-13T20:55:23+00:00","og_image":[{"width":346,"height":300,"url":"https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/ICEVI\u2013WBU-thumb.jpg","type":"image\/jpeg"}],"author":"Natacha","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Natacha","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/#article","isPartOf":{"@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/"},"author":{"name":"Natacha","@id":"https:\/\/www.humanware.com\/fr\/#\/schema\/person\/d38997639f2af0f29e505b296196f4a7"},"headline":"Soutenir un mouvement mondial pour la litt\u00e9ratie braille","datePublished":"2026-01-10T20:07:31+00:00","dateModified":"2026-01-13T20:55:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/"},"wordCount":562,"publisher":{"@id":"https:\/\/www.humanware.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/ICEVI\u2013WBU-thumb.jpg","articleSection":["Nouvelles","Nouvelles de l'entreprise"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/","url":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/","name":"Soutenir un mouvement mondial pour la litt\u00e9ratie braille - HumanWare","isPartOf":{"@id":"https:\/\/www.humanware.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/#primaryimage"},"image":{"@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/ICEVI\u2013WBU-thumb.jpg","datePublished":"2026-01-10T20:07:31+00:00","dateModified":"2026-01-13T20:55:23+00:00","description":"HumanWare est fi\u00e8re de soutenir la campagne mondiale pour la litt\u00e9ratie braille ICEVI\u2013WBU en tant que commanditaire Diamant, et de se joindre \u00e0 un mouvement international d\u00e9di\u00e9 \u00e0 l\u2019avancement de la litt\u00e9ratie braille et de l\u2019inclusion des personnes qui sont aveugles, sourdes-aveugles ou qui ont une basse vision.","breadcrumb":{"@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/#primaryimage","url":"https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/ICEVI\u2013WBU-thumb.jpg","contentUrl":"https:\/\/www.humanware.com\/wp-content\/uploads\/2026\/01\/ICEVI\u2013WBU-thumb.jpg","width":346,"height":300,"caption":"Un enfant africain utilise un appareil braille en classe, accompagn\u00e9 de son enseignante."},{"@type":"BreadcrumbList","@id":"https:\/\/www.humanware.com\/fr\/nouvelles\/supporting-global-movement-for-braille-literacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.humanware.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/www.humanware.com\/fr\/category\/nouvelles\/"},{"@type":"ListItem","position":3,"name":"Soutenir un mouvement mondial pour la litt\u00e9ratie braille"}]},{"@type":"WebSite","@id":"https:\/\/www.humanware.com\/fr\/#website","url":"https:\/\/www.humanware.com\/fr\/","name":"HumanWare","description":"Solutions pour basse vision et c\u00e9cit\u00e9","publisher":{"@id":"https:\/\/www.humanware.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.humanware.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.humanware.com\/fr\/#organization","name":"HumanWare","url":"https:\/\/www.humanware.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.humanware.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.humanware.com\/wp-content\/uploads\/2024\/12\/Logo-HW.jpg","contentUrl":"https:\/\/www.humanware.com\/wp-content\/uploads\/2024\/12\/Logo-HW.jpg","width":1000,"height":667,"caption":"HumanWare"},"image":{"@id":"https:\/\/www.humanware.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/humanware\/","https:\/\/ca.linkedin.com\/company\/humanware"]},{"@type":"Person","@id":"https:\/\/www.humanware.com\/fr\/#\/schema\/person\/d38997639f2af0f29e505b296196f4a7","name":"Natacha","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/609632888407e6eb44e59b600082fb4bd01895796c5293abded07e5942c828a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/609632888407e6eb44e59b600082fb4bd01895796c5293abded07e5942c828a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/609632888407e6eb44e59b600082fb4bd01895796c5293abded07e5942c828a9?s=96&d=mm&r=g","caption":"Natacha"}}]}},"_links":{"self":[{"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/posts\/17915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/comments?post=17915"}],"version-history":[{"count":9,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/posts\/17915\/revisions"}],"predecessor-version":[{"id":17927,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/posts\/17915\/revisions\/17927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/media\/17875"}],"wp:attachment":[{"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/media?parent=17915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/categories?post=17915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.humanware.com\/fr\/wp-json\/wp\/v2\/tags?post=17915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}